{"id":6349,"date":"2019-10-06T13:29:40","date_gmt":"2019-10-06T11:29:40","guid":{"rendered":"http:\/\/www.fondationassistanceauxanimaux.org\/actu\/?p=6349"},"modified":"2019-10-06T13:29:40","modified_gmt":"2019-10-06T11:29:40","slug":"chaton-leucose-refuge-villevaude","status":"publish","type":"post","link":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/","title":{"rendered":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation."},"content":{"rendered":"<p><b>Retrouv\u00e9 abandonn\u00e9 sur un parking, ce petit a \u00e9t\u00e9 pris en charge par notre refuge de Villevaud\u00e9.\u00a0<\/b><\/p>\n<div><b>\u00ab Picco \u00bb est une machine \u00e0 ronronner de 4 mois au poil mi-long.\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Malheureusement il est touch\u00e9 par le virus de la leucose&#8230; Ce virus aussi appel\u00e9 FeLV a une action proche de celle du sida chez l&rsquo;homme.\u00a0<\/b><\/div>\n<div><b>N\u00e9anmoins, il n\u2019y a aucune transmission possible du chat \u00e0 l\u2019homme, ni du chat \u00e0 aucune autre esp\u00e8ce animale. Le virus n\u2019atteint que les chats.\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Il n\u2019y a pas de traitement possible. \u00ab Picco \u00bb vivra moins longtemps.\u00a0<\/b><\/div>\n<div><b>Nous recherchons un(e) adoptant(e) qui lui offrira la plus belle des vies.\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Vous l\u2019avez compris, il ne faut pas d\u2019autres chats \u00e0 la maison et il doit vivre en appartement.\u00a0<\/b><\/div>\n<div><b>\u00a0<\/b><\/div>\n<div><b>Notre refuge est ouvert aujourd\u2019hui, \u00ab Picco \u00bb vous attend.<\/b><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Retrouv\u00e9 abandonn\u00e9 sur un parking, ce petit a \u00e9t\u00e9 pris en charge par notre refuge de Villevaud\u00e9.\u00a0 \u00ab Picco \u00bb est une machine \u00e0 ronronner de 4 mois au poil mi-long.\u00a0 \u00a0 Malheureusement il est touch\u00e9 par le virus de la leucose&#8230; Ce virus aussi appel\u00e9 FeLV a une action proche de celle du sida [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6350,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21,20],"tags":[],"class_list":["post-6349","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fondation-assistance-aux-animaux","category-refuge-de-villevaude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce petit a \u00e9t\u00e9 pris en charge par notre refuge de Villevaud\u00e9.\u00a0 \u00ab Picco \u00bb est une machine \u00e0 ronronner de 4 mois au poil mi-long.\u00a0 \u00a0 Malheureusement il est touch\u00e9 par le virus de la leucose&#8230; Ce virus aussi appel\u00e9 FeLV a une action proche de celle du sida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-06T11:29:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"628\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/\",\"name\":\"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg\",\"datePublished\":\"2019-10-06T11:29:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg\",\"contentUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg\",\"width\":628,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\",\"name\":\"Fondation Assistance aux Animaux - Actualit\u00e9s\",\"description\":\"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\",\"name\":\"No\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"caption\":\"No\u00e9\"},\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/","og_locale":"fr_FR","og_type":"article","og_title":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","og_description":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce petit a \u00e9t\u00e9 pris en charge par notre refuge de Villevaud\u00e9.\u00a0 \u00ab Picco \u00bb est une machine \u00e0 ronronner de 4 mois au poil mi-long.\u00a0 \u00a0 Malheureusement il est touch\u00e9 par le virus de la leucose&#8230; Ce virus aussi appel\u00e9 FeLV a une action proche de celle du sida [&hellip;]","og_url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/","og_site_name":"Fondation Assistance aux Animaux - Actualit\u00e9s","article_published_time":"2019-10-06T11:29:40+00:00","og_image":[{"width":628,"height":750,"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg","type":"image\/jpeg"}],"author":"No\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"No\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/","name":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg","datePublished":"2019-10-06T11:29:40+00:00","author":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b"},"breadcrumb":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#primaryimage","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg","contentUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/10\/72616707_2466151090131896_2613953964344868864_n.jpg","width":628,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chaton-leucose-refuge-villevaude-6349\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/"},{"@type":"ListItem","position":2,"name":"Retrouv\u00e9 abandonn\u00e9 sur un parking, ce chaton, touch\u00e9 par le virus de la leucose, a \u00e9t\u00e9 pris en charge par la Fondation."}]},{"@type":"WebSite","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/","name":"Fondation Assistance aux Animaux - Actualit\u00e9s","description":"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b","name":"No\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","caption":"No\u00e9"},"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/comments?post=6349"}],"version-history":[{"count":2,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6349\/revisions"}],"predecessor-version":[{"id":6352,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6349\/revisions\/6352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media\/6350"}],"wp:attachment":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media?parent=6349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/categories?post=6349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/tags?post=6349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}