{"id":6124,"date":"2019-09-09T16:57:17","date_gmt":"2019-09-09T14:57:17","guid":{"rendered":"http:\/\/www.fondationassistanceauxanimaux.org\/actu\/?p=6124"},"modified":"2019-09-09T16:59:40","modified_gmt":"2019-09-09T14:59:40","slug":"chiot-tue-ardeche","status":"publish","type":"post","link":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/","title":{"rendered":"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s."},"content":{"rendered":"<p><b>Lundi 26 ao\u00fbt, un border collie de 4 mois est mort sous les balles d&rsquo;un chasseur \u00e0 Saint-Agr\u00e8ve (07) en Ard\u00e8che. Le tireur, \u00e2g\u00e9 de 22 ans a reconnu les faits et devra r\u00e9pondre de ses actes le 14 f\u00e9vrier au tribunal de Privas, la Fondation Assistance aux Animaux, partie civile, sera pr\u00e9sente.<\/b><\/p>\n<p><b>L&rsquo;individu est poursuivi pour \u00ab acte de cruaut\u00e9 envers un animal domestique \u00bb. Il se promenait lorsqu&rsquo;il a entendu un chien aboyer, il serait alors rentr\u00e9 chez lui pour prendre sa carabine et l&rsquo;a abattu de deux balles afin de le faire taire. Selon le jeune homme, le chien aurait pu \u00ab perturber le gibier en aboyant \u00bb car la chasse ouvrait le dimanche d&rsquo;apr\u00e8s.<\/b><\/p>\n<p><b>Le ma\u00eetre de Kinder, un retrait\u00e9 de 66 ans a entendu un coup de feu, puis les hurlements d&rsquo;un chien, en l\u2019occurrence ceux de Kinder. Puis une deuxi\u00e8me d\u00e9tonation a retenti suivi d&rsquo;un grand silence&#8230; Alert\u00e9, il a imm\u00e9diatement contact\u00e9 la gendarmerie et s&rsquo;est rendu sur place o\u00f9 il a d\u00e9couvert la voiture d&rsquo;un chasseur. Dans le m\u00eame temps son \u00e9pouse est parvenue \u00e0 arr\u00eater le tireur. En attendant l&rsquo;arriv\u00e9e des forces de l&rsquo;ordre, le sexag\u00e9naire a plac\u00e9 son tracteur de fa\u00e7on \u00e0 bloquer le v\u00e9hicule.<\/b><\/p>\n<p><b>Les gendarmes ont d\u00e9couvert une carabine \u00e0 l&rsquo;int\u00e9rieur du v\u00e9hicule, ils ont \u00e9galement interrog\u00e9 l&rsquo;auteur des coups de feu qui a reconnu avoir tu\u00e9 le chien mais aussi avoir tent\u00e9 de faire dispara\u00eetre le corps de l&rsquo;animal.<\/b><\/p>\n<p><b>Sa carabine lui a \u00e9t\u00e9 confisqu\u00e9e mais il a tout de m\u00eame conserv\u00e9 son permis de chasse et son port d&rsquo;arme. Le comble dans cette histoire c&rsquo;est que ce jeune homme a pu participer \u00e0 l&rsquo;ouverture de la chasse ce dimanche 8 septembre.<\/b><\/p>\n<p><b>La Fondation Assistance aux Animaux reste choqu\u00e9e d&rsquo;un tel acte et ne comprend pas que ce jeune homme puisse continuer \u00e0 chasser et \u00e0 porter une arme.<br \/>\nLa p\u00e9riode de chasse d\u00e9bute et comme chaque ann\u00e9e, les for\u00eats seront restreintes au b\u00e9n\u00e9fice des chasseurs et nombreux seront les humains et les animaux domestiques victimes de tirs.\u00a0\u00a0<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lundi 26 ao\u00fbt, un border collie de 4 mois est mort sous les balles d&rsquo;un chasseur \u00e0 Saint-Agr\u00e8ve (07) en Ard\u00e8che. Le tireur, \u00e2g\u00e9 de 22 ans a reconnu les faits et devra r\u00e9pondre de ses actes le 14 f\u00e9vrier au tribunal de Privas, la Fondation Assistance aux Animaux, partie civile, sera pr\u00e9sente. L&rsquo;individu est [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":6125,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-6124","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fondation-assistance-aux-animaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Lundi 26 ao\u00fbt, un border collie de 4 mois est mort sous les balles d&rsquo;un chasseur \u00e0 Saint-Agr\u00e8ve (07) en Ard\u00e8che. Le tireur, \u00e2g\u00e9 de 22 ans a reconnu les faits et devra r\u00e9pondre de ses actes le 14 f\u00e9vrier au tribunal de Privas, la Fondation Assistance aux Animaux, partie civile, sera pr\u00e9sente. L&rsquo;individu est [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-09T14:57:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-09T14:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"838\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/\",\"name\":\"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg\",\"datePublished\":\"2019-09-09T14:57:17+00:00\",\"dateModified\":\"2019-09-09T14:59:40+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg\",\"contentUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg\",\"width\":900,\"height\":838},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\",\"name\":\"Fondation Assistance aux Animaux - Actualit\u00e9s\",\"description\":\"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\",\"name\":\"No\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"caption\":\"No\u00e9\"},\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/","og_locale":"fr_FR","og_type":"article","og_title":"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s","og_description":"Lundi 26 ao\u00fbt, un border collie de 4 mois est mort sous les balles d&rsquo;un chasseur \u00e0 Saint-Agr\u00e8ve (07) en Ard\u00e8che. Le tireur, \u00e2g\u00e9 de 22 ans a reconnu les faits et devra r\u00e9pondre de ses actes le 14 f\u00e9vrier au tribunal de Privas, la Fondation Assistance aux Animaux, partie civile, sera pr\u00e9sente. L&rsquo;individu est [&hellip;]","og_url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/","og_site_name":"Fondation Assistance aux Animaux - Actualit\u00e9s","article_published_time":"2019-09-09T14:57:17+00:00","article_modified_time":"2019-09-09T14:59:40+00:00","og_image":[{"width":900,"height":838,"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg","type":"image\/jpeg"}],"author":"No\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"No\u00e9","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/","name":"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s. - Fondation Assistance aux Animaux - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg","datePublished":"2019-09-09T14:57:17+00:00","dateModified":"2019-09-09T14:59:40+00:00","author":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b"},"breadcrumb":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#primaryimage","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg","contentUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/09\/kinder.jpg","width":900,"height":838},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/chiot-tue-ardeche-6124\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/"},{"@type":"ListItem","position":2,"name":"Un chiot a \u00e9t\u00e9 tu\u00e9 par un chasseur car il aboyait trop fort. La Fondation Assistance aux Animaux sera pr\u00e9sente au proc\u00e8s."}]},{"@type":"WebSite","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/","name":"Fondation Assistance aux Animaux - Actualit\u00e9s","description":"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b","name":"No\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","caption":"No\u00e9"},"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/comments?post=6124"}],"version-history":[{"count":3,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6124\/revisions"}],"predecessor-version":[{"id":6131,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/6124\/revisions\/6131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media\/6125"}],"wp:attachment":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media?parent=6124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/categories?post=6124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/tags?post=6124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}