{"id":4141,"date":"2019-03-01T18:56:38","date_gmt":"2019-03-01T17:56:38","guid":{"rendered":"http:\/\/www.fondationassistanceauxanimaux.org\/actu\/?p=4141"},"modified":"2019-03-01T18:57:53","modified_gmt":"2019-03-01T17:57:53","slug":"sauvetage-chats-cage-lapin","status":"publish","type":"post","link":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/","title":{"rendered":"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation."},"content":{"rendered":"<p><b>L&rsquo;\u00e9quipe protection animale de la Fondation Assistance aux Animaux est intervenue ce matin dans une propri\u00e9t\u00e9 des Hauts-de-Seine pour secourir une dizaine d&rsquo;animaux d\u00e9tenus dans des conditions intol\u00e9rables.<\/p>\n<p>Ce sont divers signalements d&rsquo;acheteurs qui ont permis de mettre en lumi\u00e8re un trafic de chats aggrav\u00e9 par des conditions de d\u00e9tentions honteuses.<\/p>\n<p>Propos\u00e9s entre 160\u20ac et 220\u20ac, uniquement payables en esp\u00e8ces, des dizaines de chats ont ainsi \u00e9t\u00e9 vendus apr\u00e8s avoir s\u00e9journ\u00e9 dans l&rsquo;habitation de cette particuli\u00e8re qui se dit fervente d\u00e9fenseuse de la cause animale.<\/p>\n<p>Les chats vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapins dont ils ne sortaient jamais !<br \/>\nCertains en furent prisonniers depuis de longues ann\u00e9es, d&rsquo;autres \u00e9taient reclus \u00e0 la cave dans l&rsquo;obscurit\u00e9 la plus compl\u00e8te.<\/p>\n<p>Un lapin et des oiseaux, sans eau et dans une cage au sol recouverte de fientes ont \u00e9galement pu \u00eatre pris en charge par la Fondation.<\/p>\n<p>D\u00e9sormais \u00e0 l&rsquo;abris, et ne connaissant que les quelques centim\u00e8tres carr\u00e9s de leur cage, il leur faudra du temps avant de s&rsquo;adapter aux grands espaces des chatteries.<\/p>\n<p>La Fondation d\u00e9plore que des personnes continuent d&rsquo;alimenter le trafic d&rsquo;animaux en achetant \u00e0 des particuliers.<br \/>\nNous rappelons que sans offres, il n&rsquo;y a pas de demandes.<\/p>\n<p>Nous avons bien entendu d\u00e9pos\u00e9 plainte contre leur d\u00e9tentrice.<\/b><\/p>\n<p><a href=\"https:\/\/jesoutiens.fondationassistanceauxanimaux.org\/dons\/~mon-don\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1964 size-full\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/02\/soutiens.png\" alt=\"\" width=\"204\" height=\"46\" \/><\/a><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4144\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-1030x773.jpg\" alt=\"\" width=\"825\" height=\"619\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-1030x773.jpg 1030w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-768x576.jpg 768w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-1500x1125.jpg 1500w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-705x529.jpg 705w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26601-450x338.jpg 450w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4145\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26661.jpg\" alt=\"\" width=\"583\" height=\"437\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26661.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26661-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26661-450x338.jpg 450w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4146\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26781.jpg\" alt=\"\" width=\"592\" height=\"444\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26781.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26781-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26781-450x338.jpg 450w\" sizes=\"auto, (max-width: 592px) 100vw, 592px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-4147\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26821.jpg\" alt=\"\" width=\"601\" height=\"451\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26821.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26821-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26821-450x338.jpg 450w\" sizes=\"auto, (max-width: 601px) 100vw, 601px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4149\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26881.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26881.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26881-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26881-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4150\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26891.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26891.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26891-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26891-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4151\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26971.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26971.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26971-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26971-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4152\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26991.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26991.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26991-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26991-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4153\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27031.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27031.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27031-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27031-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4154\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27041.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27041.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27041-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27041-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4155\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27061.jpg\" alt=\"\" width=\"640\" height=\"480\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27061.jpg 640w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27061-300x225.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_27061-450x338.jpg 450w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" \/><\/p>\n<p><a href=\"https:\/\/jesoutiens.fondationassistanceauxanimaux.org\/dons\/~mon-don\/\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-1964 size-full\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/02\/soutiens.png\" alt=\"\" width=\"204\" height=\"46\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9quipe protection animale de la Fondation Assistance aux Animaux est intervenue ce matin dans une propri\u00e9t\u00e9 des Hauts-de-Seine pour secourir une dizaine d&rsquo;animaux d\u00e9tenus dans des conditions intol\u00e9rables. Ce sont divers signalements d&rsquo;acheteurs qui ont permis de mettre en lumi\u00e8re un trafic de chats aggrav\u00e9 par des conditions de d\u00e9tentions honteuses. Propos\u00e9s entre 160\u20ac et [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4142,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-4141","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fondation-assistance-aux-animaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;\u00e9quipe protection animale de la Fondation Assistance aux Animaux est intervenue ce matin dans une propri\u00e9t\u00e9 des Hauts-de-Seine pour secourir une dizaine d&rsquo;animaux d\u00e9tenus dans des conditions intol\u00e9rables. Ce sont divers signalements d&rsquo;acheteurs qui ont permis de mettre en lumi\u00e8re un trafic de chats aggrav\u00e9 par des conditions de d\u00e9tentions honteuses. Propos\u00e9s entre 160\u20ac et [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-01T17:56:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-01T17:57:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/\",\"name\":\"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg\",\"datePublished\":\"2019-03-01T17:56:38+00:00\",\"dateModified\":\"2019-03-01T17:57:53+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg\",\"contentUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg\",\"width\":640,\"height\":480},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\",\"name\":\"Fondation Assistance aux Animaux - Actualit\u00e9s\",\"description\":\"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\",\"name\":\"No\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"caption\":\"No\u00e9\"},\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/","og_locale":"fr_FR","og_type":"article","og_title":"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","og_description":"L&rsquo;\u00e9quipe protection animale de la Fondation Assistance aux Animaux est intervenue ce matin dans une propri\u00e9t\u00e9 des Hauts-de-Seine pour secourir une dizaine d&rsquo;animaux d\u00e9tenus dans des conditions intol\u00e9rables. Ce sont divers signalements d&rsquo;acheteurs qui ont permis de mettre en lumi\u00e8re un trafic de chats aggrav\u00e9 par des conditions de d\u00e9tentions honteuses. Propos\u00e9s entre 160\u20ac et [&hellip;]","og_url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/","og_site_name":"Fondation Assistance aux Animaux - Actualit\u00e9s","article_published_time":"2019-03-01T17:56:38+00:00","article_modified_time":"2019-03-01T17:57:53+00:00","og_image":[{"width":640,"height":480,"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg","type":"image\/jpeg"}],"author":"No\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"No\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/","name":"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation. - Fondation Assistance aux Animaux - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg","datePublished":"2019-03-01T17:56:38+00:00","dateModified":"2019-03-01T17:57:53+00:00","author":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b"},"breadcrumb":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#primaryimage","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg","contentUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/03\/IMG_26861.jpg","width":640,"height":480},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-chats-cage-lapin-4141\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/"},{"@type":"ListItem","position":2,"name":"Ils vivaient clo\u00eetr\u00e9s dans des cages \u00e0 lapin : une dizaine de chats ont \u00e9t\u00e9 saisis par la Fondation."}]},{"@type":"WebSite","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/","name":"Fondation Assistance aux Animaux - Actualit\u00e9s","description":"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b","name":"No\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","caption":"No\u00e9"},"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/comments?post=4141"}],"version-history":[{"count":4,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4141\/revisions"}],"predecessor-version":[{"id":4224,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4141\/revisions\/4224"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media\/4142"}],"wp:attachment":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media?parent=4141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/categories?post=4141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/tags?post=4141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}