{"id":4042,"date":"2019-02-21T17:11:38","date_gmt":"2019-02-21T16:11:38","guid":{"rendered":"http:\/\/www.fondationassistanceauxanimaux.org\/actu\/?p=4042"},"modified":"2019-02-21T17:13:28","modified_gmt":"2019-02-21T16:13:28","slug":"jugement-paco-chien-prisonnier","status":"publish","type":"post","link":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/","title":{"rendered":"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d&rsquo;\u00eatre condamn\u00e9e."},"content":{"rendered":"<div>\n<div><b>Suite \u00e0 sa s\u00e9paration, la propri\u00e9taire de ce dogue argentin \u00e2g\u00e9 de 3 ans l\u2019a laiss\u00e9 dans l&rsquo;appartement conjugale inhabit\u00e9.<br \/>\nNe supportant plus les \u00ab b\u00eatises \u00bb que faisait ce pauvre chien, elle a d\u00e9cid\u00e9 de l\u2019enfermer entre le volet et la baie vitr\u00e9e de son habitation.<\/p>\n<p>\u00ab Paco \u00bb est alors rest\u00e9 plus d\u2019un mois, livr\u00e9 \u00e0 lui-m\u00eame dans cet espace inimaginable de m\u00eame pas 30cm de largeur, dans ses excr\u00e9ments, sans eau ni nourriture !<br \/>\nC\u2019est un v\u00e9ritable calvaire qu\u2019\u00e0 v\u00e9cu ce chien, il ne pesait plus que 23 kilos lors de sa saisie\u2026 (le poids moyen est de 45kg).<\/p>\n<p>Il s\u2019est battu tant bien que mal pour rester en vie.<br \/>\nCette sordide histoire remonte au mois de juin 2018 o\u00f9 par de fortes chaleurs, les g\u00e9missements et appels \u00e0 l\u2019aide de ce pauvre loulou l\u2019ont finalement sauv\u00e9 puisqu\u2019une voisine a lanc\u00e9 l\u2019alerte.<\/p>\n<p>Le proc\u00e8s a eu lieu et la Fondation Assistance aux Animaux, constitu\u00e9e partie civile, \u00e9tait sur les lieux.<br \/>\nUne fois de plus, le verdict est tr\u00e8s d\u00e9cevant :<\/p>\n<p>&#8211; 1 mois de prison avec sursis<br \/>\n&#8211; 5 ans d\u2019interdiction de d\u00e9tenir un animal<\/p>\n<p>Quand est-ce que la souffrance animale sera v\u00e9ritablement consid\u00e9r\u00e9e ?<\/b><\/div>\n<div><\/div>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-4043\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-957x1030.png\" alt=\"\" width=\"957\" height=\"1030\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-957x1030.png 957w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-279x300.png 279w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-768x826.png 768w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-655x705.png 655w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00-450x484.png 450w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/Capture-d\u2019e\u0301cran-2019-02-21-a\u0300-16.52.00.png 1208w\" sizes=\"auto, (max-width: 957px) 100vw, 957px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Suite \u00e0 sa s\u00e9paration, la propri\u00e9taire de ce dogue argentin \u00e2g\u00e9 de 3 ans l\u2019a laiss\u00e9 dans l&rsquo;appartement conjugale inhabit\u00e9. Ne supportant plus les \u00ab b\u00eatises \u00bb que faisait ce pauvre chien, elle a d\u00e9cid\u00e9 de l\u2019enfermer entre le volet et la baie vitr\u00e9e de son habitation. \u00ab Paco \u00bb est alors rest\u00e9 plus d\u2019un [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4044,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-4042","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fondation-assistance-aux-animaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d&#039;\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d&#039;\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"Suite \u00e0 sa s\u00e9paration, la propri\u00e9taire de ce dogue argentin \u00e2g\u00e9 de 3 ans l\u2019a laiss\u00e9 dans l&rsquo;appartement conjugale inhabit\u00e9. Ne supportant plus les \u00ab b\u00eatises \u00bb que faisait ce pauvre chien, elle a d\u00e9cid\u00e9 de l\u2019enfermer entre le volet et la baie vitr\u00e9e de son habitation. \u00ab Paco \u00bb est alors rest\u00e9 plus d\u2019un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-21T16:11:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-21T16:13:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1025\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/\",\"name\":\"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d'\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg\",\"datePublished\":\"2019-02-21T16:11:38+00:00\",\"dateModified\":\"2019-02-21T16:13:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg\",\"contentUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg\",\"width\":1025,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d&rsquo;\u00eatre condamn\u00e9e.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\",\"name\":\"Fondation Assistance aux Animaux - Actualit\u00e9s\",\"description\":\"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\",\"name\":\"No\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"caption\":\"No\u00e9\"},\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d'\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/","og_locale":"fr_FR","og_type":"article","og_title":"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d'\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s","og_description":"Suite \u00e0 sa s\u00e9paration, la propri\u00e9taire de ce dogue argentin \u00e2g\u00e9 de 3 ans l\u2019a laiss\u00e9 dans l&rsquo;appartement conjugale inhabit\u00e9. Ne supportant plus les \u00ab b\u00eatises \u00bb que faisait ce pauvre chien, elle a d\u00e9cid\u00e9 de l\u2019enfermer entre le volet et la baie vitr\u00e9e de son habitation. \u00ab Paco \u00bb est alors rest\u00e9 plus d\u2019un [&hellip;]","og_url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/","og_site_name":"Fondation Assistance aux Animaux - Actualit\u00e9s","article_published_time":"2019-02-21T16:11:38+00:00","article_modified_time":"2019-02-21T16:13:28+00:00","og_image":[{"width":1025,"height":640,"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg","type":"image\/jpeg"}],"author":"No\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"No\u00e9","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/","name":"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d'\u00eatre condamn\u00e9e. - Fondation Assistance aux Animaux - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg","datePublished":"2019-02-21T16:11:38+00:00","dateModified":"2019-02-21T16:13:28+00:00","author":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b"},"breadcrumb":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#primaryimage","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg","contentUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2019\/02\/dogue.jpg","width":1025,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/jugement-paco-chien-prisonnier-4042\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/"},{"@type":"ListItem","position":2,"name":"Prisonnier entre un volet et une vitre, Paco a \u00e9t\u00e9 sauv\u00e9 en juin 2018. La propri\u00e9taire vient d&rsquo;\u00eatre condamn\u00e9e."}]},{"@type":"WebSite","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/","name":"Fondation Assistance aux Animaux - Actualit\u00e9s","description":"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b","name":"No\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","caption":"No\u00e9"},"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/comments?post=4042"}],"version-history":[{"count":3,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4042\/revisions"}],"predecessor-version":[{"id":4046,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/4042\/revisions\/4046"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media\/4044"}],"wp:attachment":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media?parent=4042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/categories?post=4042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/tags?post=4042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}