{"id":1801,"date":"2018-01-24T17:14:26","date_gmt":"2018-01-24T16:14:26","guid":{"rendered":"http:\/\/www.fondationassistanceauxanimaux.org\/actu\/?p=1801"},"modified":"2018-01-24T17:24:49","modified_gmt":"2018-01-24T16:24:49","slug":"sauvetage","status":"publish","type":"post","link":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/","title":{"rendered":"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper !"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1802\" src=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg\" alt=\"\" width=\"668\" height=\"355\" srcset=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg 668w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o-300x159.jpg 300w, https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o-450x239.jpg 450w\" sizes=\"auto, (max-width: 668px) 100vw, 668px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p class=\"\"><em><span class=\"\">C\u2019est une passante, interpell\u00e9e par ce chien fam\u00e9lique et affam\u00e9 qui vagabonde dans un jardin entre les excr\u00e9ments, qui a donn\u00e9 l\u2019alerte. Compte tenu de l\u2019\u00e9tat de l\u2019animal, la Fondation envoie imm\u00e9diatement un enqu\u00eateur sur les lieux. Et il lui faudra une bonne dose de patience pour garder son calme\u2026 Car la d\u00e9tentrice de l\u2019animal va se justifier d\u2019une bien dr\u00f4le de mani\u00e8re.<\/span><\/em><\/p>\n<p class=\"\"><span class=\"\"><span style=\"color: #0000ff;\">Mouss n\u2019a m\u00eame pas un an, et il a d\u00e9j\u00e0 connu la faim, la maltraitance, et l\u2019abandon . Voil\u00e0 ce qui se passe quand on donne son animal \u00ab\u00a0contre bon soin\u00a0\u00bb sur les sites d\u2019annonces en ligne\u2026.<\/span><\/span><\/p>\n<p class=\"\"><span class=\"\">Refil\u00e9 comme une marchandise de mains en mains sur le bon coin, (il est d\u00e9j\u00e0 pass\u00e9 par au moins 3 familles\u00a0en seulement quelques mois! ), il a fini par atterrir chez cette famille de Li\u00e9vin par l\u2019interm\u00e9diaire de la fille, coll\u00e9gienne, qui l\u2019a r\u00e9cup\u00e9r\u00e9 via une annonce facebook.<\/span><\/p>\n<p class=\"\"><span class=\"\">Cela ferait maintenant plusieurs semaines qu\u2019il est dans ce nouveau foyer, et le moins que l\u2019on puisse dire c\u2019est que son \u00e9tat physique n\u2019est pas bon du tout. Il est maigre \u00e0 faire peur, on peut lui compter les c\u00f4tes.<\/span><span class=\"\"><span style=\"color: #0000ff;\">\u00a0<\/span><\/span><\/p>\n<p class=\"\"><span class=\"\"><span style=\"color: #0000ff;\">Craintif, il ne se laisse pas approcher, sauf avec de la nourriture tant la faim prend le pas sur sa s\u00e9curit\u00e9.<\/span><\/span><span class=\"\">\u00a0Mais pourquoi ce chien est-il si maigre\u00a0? \u00a0\u00ab\u00a0<\/span><span class=\"\">Je ne sais pas, ce n\u2019est pas moi qui m\u2019en occupe, c\u2019est ma fille. C\u2019est elle qui l\u2019a ramen\u00e9 il y\u2019a plus d\u2019un mois<\/span><span class=\"\">\u00a0\u00bb L\u00e0 o\u00f9 le b\u00e2t blesse, c\u2019est que la fille en question n\u2019a que 12 ans\u00a0!!!<\/span><\/p>\n<p class=\"\"><span class=\"\">Finalement, face au discours incoh\u00e9rent de la d\u00e9tentrice qui d\u00e9charge toute la responsabilit\u00e9 sur sa fille mineure, \u00e0 son incapacit\u00e9 \u00e0 fournir le moindre document sur ce chien qui n\u2019est ni identifi\u00e9, ni suivi par un v\u00e9t\u00e9rinaire, et ne disposant d\u2019aucun acte de cession, la d\u00e9cision sera prise de repartir avec l\u2019animal afin de lui prodiguer les meilleurs soins possibles.<\/span><\/p>\n<p class=\"\"><span class=\"\"><span style=\"color: #0000ff;\">Pris en charge par Fondation Assistance aux Animaux \u2013 refuge de Villevaud\u00e9, Mouss va reprendre des forces avant d\u2019\u00eatre propos\u00e9 \u00e0 l\u2019adoption dans une famille s\u00e9rieuse et responsable qui aura bien conscience des besoins et du cout que n\u00e9cessitent un animal.<\/span><\/span><\/p>\n<div class=\"\">\n<div class=\"\" dir=\"ltr\">\n<p class=\"\"><span class=\"\">On ne le dira jamais assez\u00a0: Ne confiez pas vos prot\u00e9g\u00e9s \u00e0 n\u2019importe qui, et encore moins via des annonces en lignes\u00a0! Mouss a eu de la chance, mais combien d\u2019autres se retrouvent ainsi entre de mauvaises mains\u00a0?<\/span><\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; C\u2019est une passante, interpell\u00e9e par ce chien fam\u00e9lique et affam\u00e9 qui vagabonde dans un jardin entre les excr\u00e9ments, qui a donn\u00e9 l\u2019alerte. Compte tenu de l\u2019\u00e9tat de l\u2019animal, la Fondation envoie imm\u00e9diatement un enqu\u00eateur sur les lieux. Et il lui faudra une bonne dose de patience pour garder son calme\u2026 Car la d\u00e9tentrice de [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1802,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-fondation-assistance-aux-animaux"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"og:description\" content=\"&nbsp; C\u2019est une passante, interpell\u00e9e par ce chien fam\u00e9lique et affam\u00e9 qui vagabonde dans un jardin entre les excr\u00e9ments, qui a donn\u00e9 l\u2019alerte. Compte tenu de l\u2019\u00e9tat de l\u2019animal, la Fondation envoie imm\u00e9diatement un enqu\u00eateur sur les lieux. Et il lui faudra une bonne dose de patience pour garder son calme\u2026 Car la d\u00e9tentrice de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondation Assistance aux Animaux - Actualit\u00e9s\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-24T16:14:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-24T16:24:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"668\" \/>\n\t<meta property=\"og:image:height\" content=\"355\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"No\u00e9\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"No\u00e9\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/\",\"name\":\"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s\",\"isPartOf\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg\",\"datePublished\":\"2018-01-24T16:14:26+00:00\",\"dateModified\":\"2018-01-24T16:24:49+00:00\",\"author\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg\",\"contentUrl\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg\",\"width\":668,\"height\":355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website\",\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/\",\"name\":\"Fondation Assistance aux Animaux - Actualit\u00e9s\",\"description\":\"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b\",\"name\":\"No\u00e9\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g\",\"caption\":\"No\u00e9\"},\"url\":\"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/","og_locale":"fr_FR","og_type":"article","og_title":"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s","og_description":"&nbsp; C\u2019est une passante, interpell\u00e9e par ce chien fam\u00e9lique et affam\u00e9 qui vagabonde dans un jardin entre les excr\u00e9ments, qui a donn\u00e9 l\u2019alerte. Compte tenu de l\u2019\u00e9tat de l\u2019animal, la Fondation envoie imm\u00e9diatement un enqu\u00eateur sur les lieux. Et il lui faudra une bonne dose de patience pour garder son calme\u2026 Car la d\u00e9tentrice de [&hellip;]","og_url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/","og_site_name":"Fondation Assistance aux Animaux - Actualit\u00e9s","article_published_time":"2018-01-24T16:14:26+00:00","article_modified_time":"2018-01-24T16:24:49+00:00","og_image":[{"width":668,"height":355,"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg","type":"image\/jpeg"}],"author":"No\u00e9","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"No\u00e9","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/","name":"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper ! - Fondation Assistance aux Animaux - Actualit\u00e9s","isPartOf":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage"},"image":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage"},"thumbnailUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg","datePublished":"2018-01-24T16:14:26+00:00","dateModified":"2018-01-24T16:24:49+00:00","author":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b"},"breadcrumb":{"@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#primaryimage","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg","contentUrl":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-content\/uploads\/2018\/01\/26854002_1606706729377858_929862498_o.jpg","width":668,"height":355},{"@type":"BreadcrumbList","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/sauvetage-1801\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/"},{"@type":"ListItem","position":2,"name":"Sauvetage : Son chien est squelettique \u2013 elle se justifie en expliquant que c\u2019est \u00e0 sa fille de 12 ans de s\u2019en occuper !"}]},{"@type":"WebSite","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#website","url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/","name":"Fondation Assistance aux Animaux - Actualit\u00e9s","description":"Depuis 1930 la Fondation Assistance aux Animaux pour la d\u00e9fense et la protection des animaux maltrait\u00e9s et abandonn\u00e9s","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/71a8476d98daaea0d71a965c5603e10b","name":"No\u00e9","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d34cf6c6bd22b3db9c932bc580c4d1ba93c0cda7588a41b59078888ab1e5f007?s=96&d=mm&r=g","caption":"No\u00e9"},"url":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/author\/anne\/"}]}},"_links":{"self":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/1801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/comments?post=1801"}],"version-history":[{"count":9,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/1801\/revisions"}],"predecessor-version":[{"id":1813,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/posts\/1801\/revisions\/1813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media\/1802"}],"wp:attachment":[{"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/media?parent=1801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/categories?post=1801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fondationassistanceauxanimaux.org\/actu\/wp-json\/wp\/v2\/tags?post=1801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}